{"id":61269,"date":"2022-02-15T09:40:51","date_gmt":"2022-02-15T01:40:51","guid":{"rendered":"https:\/\/renhotecpro.com\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc"},"modified":"2022-02-15T09:40:51","modified_gmt":"2022-02-15T01:40:51","slug":"%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc","status":"publish","type":"product","link":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/","title":{"rendered":"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12"},"content":{"rendered":"<p>\u0421\u0435\u0440\u0438\u044f \u043f\u0430\u043d\u0435\u043b\u044c\u043d\u044b\u0445 \u0440\u043e\u0437\u0435\u0442\u043e\u043a M12 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0442\u0440\u0438 \u0432\u0438\u0434\u0430 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f \u043d\u0430 \u0432\u044b\u0431\u043e\u0440: PCB Mount, Panel Mount &amp; Cable, \u0438 \u0438\u043c\u0435\u044e\u0442 \u0442\u0440\u0438 \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e\u0441\u0442\u0438 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f: \u041f\u0435\u0440\u0435\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0437\u0430\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0444\u043b\u0430\u043d\u0435\u0446 \u0441 4 \u043e\u0442\u0432\u0435\u0440\u0441\u0442\u0438\u044f\u043c\u0438. \u0412 \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0438 \u0441\u043e \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u043e\u043c IEC 61076-2-101\/104, \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0443\u0435\u0442 \u0443\u0440\u043e\u0432\u043d\u044e \u0437\u0430\u0449\u0438\u0442\u044b IP67.<\/p>\n\n\t<section class=\"section\" id=\"section_942049827\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-734201991\">\n\n\n\t<div id=\"col-1659394721\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3 class=\"accordion_title\">\u0427\u0430\u0441\u0442\u043e \u0437\u0430\u0434\u0430\u0432\u0430\u0435\u043c\u044b\u0435 \u0432\u043e\u043f\u0440\u043e\u0441\u044b<\/h3><div class=\"accordion\">\n\n\t<div id=\"accordion-4061858113\" class=\"accordion-item\">\n\t\t<a id=\"accordion-4061858113-label\" class=\"accordion-title plain active\" href=\"#accordion-item-\u041a\u0430\u043a\u0438\u0435-\u0441\u0443\u0449\u0435\u0441\u0442\u0432\u0443\u044e\u0442-\u0442\u0438\u043f\u044b-\u0441\u043e\u0435\u0434\u0438\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445-\u043a\u0430\u0431\u0435\u043b\u0435\u0439-\u0441\u0435\u0440\u0438\u0438-m?\" aria-expanded=\"true\" aria-controls=\"accordion-4061858113-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u041a\u0430\u043a\u0438\u0435 \u0441\u0443\u0449\u0435\u0441\u0442\u0432\u0443\u044e\u0442 \u0442\u0438\u043f\u044b \u0441\u043e\u0435\u0434\u0438\u043d\u0438\u0442\u0435\u043b\u044c\u043d\u044b\u0445 \u043a\u0430\u0431\u0435\u043b\u0435\u0439 \u0441\u0435\u0440\u0438\u0438 M?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-4061858113-content\" class=\"accordion-inner\" style=\"display: block;\" aria-labelledby=\"accordion-4061858113-label\">\n\t\t\t\n\n<p>\u0423 \u043d\u0430\u0441 \u0435\u0441\u0442\u044c \u0440\u0430\u0437\u044a\u0435\u043c\u044b M5\/M8\/M9\/M12\/M16\/7\/8\/M23 \u0434\u043b\u044f \u043a\u0430\u0431\u0435\u043b\u0435\u0439 \u0441 \u0440\u0430\u0437\u044a\u0435\u043c\u043e\u043c M. \u0421\u0443\u0449\u0435\u0441\u0442\u0432\u0443\u044e\u0442 \u0440\u0430\u0437\u044a\u0435\u043c\u044b \u0434\u043b\u044f \u043c\u043e\u043d\u0442\u0430\u0436\u0430 \u043d\u0430 \u043f\u0430\u043d\u0435\u043b\u044c, \u043c\u043e\u043d\u0442\u0430\u0436\u043d\u044b\u0435 \u0440\u0430\u0437\u044a\u0435\u043c\u044b, \u0440\u0430\u0437\u044a\u0435\u043c\u044b \u0434\u043b\u044f \u0444\u043e\u0440\u043c\u043e\u0432\u043e\u0447\u043d\u044b\u0445 \u043a\u0430\u0431\u0435\u043b\u0435\u0439. \u041f\u043e \u043c\u0430\u0442\u0435\u0440\u0438\u0430\u043b\u0430\u043c \u043c\u044b \u043c\u043e\u0436\u0435\u043c \u0432\u044b\u0431\u0440\u0430\u0442\u044c \u043f\u043b\u0430\u0441\u0442\u0438\u043a\u043e\u0432\u044b\u0439 \u0438 \u043c\u0435\u0442\u0430\u043b\u043b\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u0442\u0438\u043f.  <\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-422005009\" class=\"accordion-item\">\n\t\t<a id=\"accordion-422005009-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u041a\u0430\u043a\u043e\u0432\u043e-\u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e-\u0434\u043e\u0441\u0442\u0443\u043f\u043d\u044b\u0445-\u043a\u043e\u043d\u0442\u0430\u043a\u0442\u043e\u0432?\" aria-expanded=\"false\" aria-controls=\"accordion-422005009-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u041a\u0430\u043a\u043e\u0432\u043e \u043a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u044b\u0445 \u043a\u043e\u043d\u0442\u0430\u043a\u0442\u043e\u0432?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-422005009-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-422005009-label\">\n\t\t\t\n\n<div>\n<h4>\u041a\u043e\u043b\u0438\u0447\u0435\u0441\u0442\u0432\u043e \u043a\u043e\u043d\u0442\u0430\u043a\u0442\u043e\u0432 \u043d\u0430\u0448\u0435\u0433\u043e \u0440\u0430\u0437\u044a\u0435\u043c\u0430 \u0441\u0435\u0440\u0438\u0438 M<\/h4>\n<div>M5: 2Pin, 3Pin, 4Pin<\/div>\n<div>M8: 2 Pin, 3Pin, 4Pin, 5Pin, 6Pin, 8Pin<\/div>\n<div>M9: 2Pin, 3Pin, 4Pin, 5Pin, 6Pin, 7Pin, 8Pin<\/div>\n<div>M12: 2Pin, 3Pin, 4Pin, 5Pin, 6Pin, 8Pin, 12Pin, 17Pin<\/div>\n<div>M16: 2Pin, 3Pin, 4Pin, 5Pin, 6Pin, 7Pin, 8Pin, 12Pin, 14Pin, 16Pin, 19Pin, 24Pin<\/div>\n<div>7\/8: 3Pin, 4Pin, 5Pin, 6Pin<\/div>\n<div>M23: 6Pin, 7Pin, 8Pin, 9Pin, 12Pin, 16Pin, 17Pin, 19Pin<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-276850556\" class=\"accordion-item\">\n\t\t<a id=\"accordion-276850556-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u041c\u043e\u0436\u043d\u043e-\u043b\u0438-\u0434\u0435\u043b\u0430\u0442\u044c-\u0434\u0432\u0443\u0445\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0438\u0439-\u043a\u0430\u0431\u0435\u043b\u044c?\" aria-expanded=\"false\" aria-controls=\"accordion-276850556-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u041c\u043e\u0436\u043d\u043e \u043b\u0438 \u0434\u0435\u043b\u0430\u0442\u044c \u0434\u0432\u0443\u0445\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0438\u0439 \u043a\u0430\u0431\u0435\u043b\u044c?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-276850556-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-276850556-label\">\n\t\t\t\n\n<p>\u0414\u0430, \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u044b \u043a\u0430\u043a \u043e\u0434\u043d\u043e\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0438\u0435, \u0442\u0430\u043a \u0438 \u0434\u0432\u0443\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0438\u0435.<\/p>\n<div class=\"row row-collapse\"  id=\"row-1983643432\">\n\n\n\t<div id=\"col-898910794\" class=\"col medium-5 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-default box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"540\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/Single-Ended-Cable-straight-e1644808377820.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/Single-Ended-Cable-straight-e1644808377820.jpg 1000w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/Single-Ended-Cable-straight-e1644808377820-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/Single-Ended-Cable-straight-e1644808377820-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/Single-Ended-Cable-straight-e1644808377820-600x324.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h4>\u041e\u0434\u043d\u043e\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0438\u0439 \u043a\u0430\u0431\u0435\u043b\u044c<\/h4>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-434923579\" class=\"col medium-5 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t\t\t\t<div class=\"\" >\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"540\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Double-Ended-Cable.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Double-Ended-Cable.jpg 1000w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Double-Ended-Cable-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Double-Ended-Cable-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Double-Ended-Cable-600x324.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\n<h4>\u0414\u0432\u0443\u0445\u043a\u043e\u043d\u0446\u0435\u0432\u043e\u0439 \u043a\u0430\u0431\u0435\u043b\u044c<\/h4>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1974946901\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1974946901-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u0415\u0441\u043b\u0438-\u0412\u0430\u0448-\u043a\u0430\u0431\u0435\u043b\u044c-\u043c\u043e\u0436\u0435\u0442-\u0431\u044b\u0442\u044c-\u044d\u043a\u0440\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u043c?\" aria-expanded=\"false\" aria-controls=\"accordion-1974946901-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u0415\u0441\u043b\u0438 \u0412\u0430\u0448 \u043a\u0430\u0431\u0435\u043b\u044c \u043c\u043e\u0436\u0435\u0442 \u0431\u044b\u0442\u044c \u044d\u043a\u0440\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u043c?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1974946901-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1974946901-label\">\n\t\t\t\n\n<p>\u0414\u0430, \u0434\u043e\u0441\u0442\u0443\u043f\u043d\u044b \u044d\u043a\u0440\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0435 \u0438 \u043d\u0435\u044d\u043a\u0440\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0435 \u0432\u0435\u0440\u0441\u0438\u0438.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-medium wp-image-34607\" src=\"http:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Cable-in-shieded-and-no-shield-2-300x162.jpg\" alt=\"\" width=\"300\" height=\"162\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Cable-in-shieded-and-no-shield-2-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Cable-in-shieded-and-no-shield-2-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Cable-in-shieded-and-no-shield-2-600x324.jpg 600w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M-Series-Cable-in-shieded-and-no-shield-2.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-1342386146\" class=\"accordion-item\">\n\t\t<a id=\"accordion-1342386146-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u041a\u0430\u043a\u043e\u0432\u0430-\u043e\u0431\u044b\u0447\u043d\u0430\u044f-\u0434\u043b\u0438\u043d\u0430-\u043a\u0430\u0431\u0435\u043b\u044f?\" aria-expanded=\"false\" aria-controls=\"accordion-1342386146-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u041a\u0430\u043a\u043e\u0432\u0430 \u043e\u0431\u044b\u0447\u043d\u0430\u044f \u0434\u043b\u0438\u043d\u0430 \u043a\u0430\u0431\u0435\u043b\u044f?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-1342386146-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-1342386146-label\">\n\t\t\t\n\n<p>0,5 \u043c \u0438\u043b\u0438 1 \u043c, \u043f\u043e\u0434\u0434\u0435\u0440\u0436\u0438\u0432\u0430\u0435\u0442\u0441\u044f \u0438 \u0434\u0440\u0443\u0433\u0430\u044f \u043d\u0435\u043e\u0431\u0445\u043e\u0434\u0438\u043c\u0430\u044f \u0412\u0430\u043c \u0434\u043b\u0438\u043d\u0430 \u043a\u0430\u0431\u0435\u043b\u044f.<\/p>\n<p> <\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t<div id=\"accordion-3280914348\" class=\"accordion-item\">\n\t\t<a id=\"accordion-3280914348-label\" class=\"accordion-title plain\" href=\"#accordion-item-\u041f\u0440\u0438\u043d\u0438\u043c\u0430\u0435\u0442\u0435-\u043b\u0438-\u0412\u044b-\u0437\u0430\u043a\u0430\u0437\u043d\u044b\u0435-\u0440\u0430\u0431\u043e\u0442\u044b?\" aria-expanded=\"false\" aria-controls=\"accordion-3280914348-content\">\n\t\t\t<button class=\"toggle\" aria-label=\"Toggle\"><i class=\"icon-angle-down\" aria-hidden=\"true\"><\/i><\/button>\n\t\t\t<span>\u041f\u0440\u0438\u043d\u0438\u043c\u0430\u0435\u0442\u0435 \u043b\u0438 \u0412\u044b \u0437\u0430\u043a\u0430\u0437\u043d\u044b\u0435 \u0440\u0430\u0431\u043e\u0442\u044b?<\/span>\n\t\t<\/a>\n\t\t<div id=\"accordion-3280914348-content\" class=\"accordion-inner\" aria-labelledby=\"accordion-3280914348-label\">\n\t\t\t\n\n<p>\u0414\u0430, \u043a\u0430\u0431\u0435\u043b\u044c \u0438\u043d\u0434\u0438\u0432\u0438\u0434\u0443\u0430\u043b\u044c\u043d\u043e\u0439 \u0434\u043b\u0438\u043d\u044b, \u0441 \u043f\u043e\u043b\u0438\u0443\u0440\u0435\u0442\u0430\u043d\u043e\u043c, \u041f\u0412\u0425, LSZH, EtherNet, profinet \u0438 \u0440\u0430\u0437\u043d\u044b\u0445 \u0446\u0432\u0435\u0442\u043e\u0432.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_942049827 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:850px) {\n  #section_942049827 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1975567028\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-113245759\">\n\n\n\t<div id=\"col-1713115543\" class=\"col medium-10 small-11 large-9\"  >\n\t\t\t\t<div class=\"col-inner text-left\" style=\"background-color:rgb(193, 230, 255);\" >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-left text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/questionnaire-line.svg\" class=\"attachment-medium size-medium\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-3247470123\" class=\"text\">\n\t\t\n\n<p><strong>\u041a\u043b\u0438\u0435\u043d\u0442<\/strong><br>\u041c\u043d\u0435 \u043d\u0443\u0436\u0435\u043d \u0434\u0432\u0443\u0441\u0442\u043e\u0440\u043e\u043d\u043d\u0438\u0439 \u044d\u043a\u0440\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0439 \u043a\u0430\u0431\u0435\u043b\u044c M12 3Pin A \u0441 \u043a\u043e\u0434\u043e\u0432\u044b\u043c \u043e\u0431\u043e\u0437\u043d\u0430\u0447\u0435\u043d\u0438\u0435\u043c \"\u043c\u0443\u0436\u0447\u0438\u043d\u0430-\u043c\u0443\u0436\u0447\u0438\u043d\u0430\", \u044d\u043a\u0440\u0430\u043d\u0438\u0440\u043e\u0432\u0430\u043d\u043d\u044b\u0439 \u043f\u043e\u043b\u0438\u0443\u0440\u0435\u0442\u0430\u043d\u043e\u043c, \u0437\u0435\u043b\u0435\u043d\u044b\u0439, 1 \u043c.  <\/p>\n\t\t\n<style>\n#text-3247470123 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1713115543 > .col-inner {\n  padding: 20px 20px 20px 20px;\n  border-radius: 12px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small align-right\"  id=\"row-379674961\">\n\n\n\t<div id=\"col-507844213\" class=\"col medium-9 small-11 large-8\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255, 243, 195);\" >\n\t\t\t\n\t\t\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-right text-right\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/question-answer-line.svg\" class=\"attachment-medium size-medium\" alt=\"\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-98020334\" class=\"text\">\n\t\t\n\n<p><strong>Renhotec Pro<\/strong><br>\u041a\u043e\u043d\u0435\u0447\u043d\u043e. \u041c\u044b \u043f\u043e\u0434\u0442\u0432\u0435\u0440\u0436\u0434\u0430\u0435\u043c \u0412\u0430\u0448\u0435 \u0442\u0440\u0435\u0431\u043e\u0432\u0430\u043d\u0438\u0435 \u0438 \u043e\u0442\u043f\u0440\u0430\u0432\u043b\u044f\u0435\u043c \u0412\u0430\u043c \u043b\u0443\u0447\u0448\u0435\u0435 \u043f\u0440\u0435\u0434\u043b\u043e\u0436\u0435\u043d\u0438\u0435. <\/p>\n\t\t\n<style>\n#text-98020334 {\n  text-align: right;\n}\n@media (min-width:550px) {\n  #text-98020334 {\n    text-align: right;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-507844213 > .col-inner {\n  padding: 20px 20px 20px 20px;\n  border-radius: 12px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1975567028 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_762707623\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"container section-title-container\" ><h3 class=\"section-title section-title-normal\"><b aria-hidden=\"true\"><\/b><span class=\"section-title-main\" >\u041e\u0431\u0440\u0430\u0437\u0446\u044b \u043f\u0435\u0440\u0441\u043e\u043d\u0430\u043b\u0438\u0437\u0430\u0446\u0438\u0438<\/span><b aria-hidden=\"true\"><\/b><\/h3><\/div>\n\n<div class=\"slider-wrapper relative\" id=\"slider-1516711861\" >\n    <div class=\"slider slider-nav-simple slider-nav-large slider-nav-light slider-style-container slider-show-nav\"\n        data-flickity-options='{\n            \"cellAlign\": \"center\",\n            \"imagesLoaded\": true,\n            \"lazyLoad\": 1,\n            \"freeScroll\": true,\n            \"wrapAround\": true,\n            \"autoPlay\": 3000,\n            \"pauseAutoPlayOnHover\" : true,\n            \"prevNextButtons\": true,\n            \"contain\" : true,\n            \"adaptiveHeight\" : true,\n            \"dragThreshold\" : 10,\n            \"percentPosition\": true,\n            \"pageDots\": true,\n            \"rightToLeft\": false,\n            \"draggable\": true,\n            \"selectedAttraction\": 0.1,\n            \"parallax\" : 0,\n            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row row-small align-middle\"  id=\"row-1922231899\">\n\n\n\t<div id=\"col-1900476128\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1811527555\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"540\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-Plastic-Purple-Cable-Male-to-Female.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-Plastic-Purple-Cable-Male-to-Female.jpg 1000w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-Plastic-Purple-Cable-Male-to-Female-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-Plastic-Purple-Cable-Male-to-Female-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-Plastic-Purple-Cable-Male-to-Female-600x324.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1811527555 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1900476128 > .col-inner {\n  margin: 8px 8px 8px 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-929041596\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-103719257\" class=\"text\">\n\t\t\n\n<h2>M12 - M12<\/h2>\r\n<ul>\r\n<li>\u041f\u043b\u0430\u0441\u0442\u0438\u043a\u043e\u0432\u044b\u0439 \u0448\u0442\u0435\u043a\u0435\u0440 \u0441 \u043c\u0443\u0436\u0441\u043a\u043e\u0433\u043e \u043d\u0430 \u0436\u0435\u043d\u0441\u043a\u0438\u0439<\/li>\r\n<li>\u0424\u0438\u043e\u043b\u0435\u0442\u043e\u0432\u044b\u0439 \u043a\u0430\u0431\u0435\u043b\u044c \u0434\u043b\u0438\u043d\u043e\u0439 1,0 \u043c<\/li>\r\n<li>\u0412\u043e\u0434\u043e\u043d\u0435\u043f\u0440\u043e\u043d\u0438\u0446\u0430\u0435\u043c\u0430\u044f \u043a\u043e\u043d\u0441\u0442\u0440\u0443\u043a\u0446\u0438\u044f \u0441\u043e \u0441\u0442\u0435\u043f\u0435\u043d\u044c\u044e \u0437\u0430\u0449\u0438\u0442\u044b IP68<\/li>\r\n<\/ul>\n\t\t\n<style>\n#text-103719257 {\n  color: rgb(0,0,0);\n}\n#text-103719257 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small align-middle\"  id=\"row-1870212582\">\n\n\n\t<div id=\"col-689829308\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1805382225\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"540\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-to-USB-RJ45-DC-USB-Cable.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-to-USB-RJ45-DC-USB-Cable.jpg 1000w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-to-USB-RJ45-DC-USB-Cable-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-to-USB-RJ45-DC-USB-Cable-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-to-USB-RJ45-DC-USB-Cable-600x324.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1805382225 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-689829308 > .col-inner {\n  margin: 8px 8px 8px 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1226985418\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-304030530\" class=\"text\">\n\t\t\n\n<h2>M12 - USB RJ45<\/h2>\r\n<ul>\r\n<li>12-\u043a\u043e\u043d\u0442\u0430\u043a\u0442\u043d\u044b\u0439 \u0448\u0442\u0435\u043a\u0435\u0440 \u0441 4 \u0432\u0438\u043b\u043a\u0430\u043c\u0438<\/li>\r\n<li>\u0412\u043e\u0434\u043e\u043d\u0435\u043f\u0440\u043e\u043d\u0438\u0446\u0430\u0435\u043c\u043e\u0441\u0442\u044c \u043f\u043e \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u0443 IP68<\/li>\r\n<li>\u0412\u044b\u0441\u043e\u043a\u043e\u043f\u0440\u043e\u0447\u043d\u044b\u0439 \u043a\u0430\u0431\u0435\u043b\u044c \u0434\u043b\u0438\u043d\u043e\u0439 1,0 \u043c<\/li>\r\n<\/ul>\n\t\t\n<style>\n#text-304030530 {\n  color: rgb(0,0,0);\n}\n#text-304030530 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small align-middle\"  id=\"row-1879150187\">\n\n\n\t<div id=\"col-629129651\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2105642555\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"540\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M8-Female-Right-Angled-Double-Ended-Cable.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M8-Female-Right-Angled-Double-Ended-Cable.jpg 1000w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M8-Female-Right-Angled-Double-Ended-Cable-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M8-Female-Right-Angled-Double-Ended-Cable-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M8-Female-Right-Angled-Double-Ended-Cable-600x324.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2105642555 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-629129651 > .col-inner {\n  margin: 8px 8px 8px 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-145037687\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-486583406\" class=\"text\">\n\t\t\n\n<h2>M8 - M8<\/h2>\n<ul>\n<li>3-\u043a\u043e\u043d\u0442\u0430\u043a\u0442\u043d\u044b\u0439 \u0440\u0430\u0437\u044a\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c \u0438 \u0433\u043d\u0435\u0437\u0434\u043e\u043c<\/li>\n<li>\u041c\u0435\u0442\u0430\u043b\u043b\u0438\u0447\u0435\u0441\u043a\u0438\u0439 \u043a\u0430\u0431\u0435\u043b\u044c \u0434\u043b\u0438\u043d\u043e\u0439 0,3 \u043c<\/li>\n<li>\u0423\u0433\u043b\u043e\u0432\u043e\u0439 \u043a\u043e\u043d\u043d\u0435\u043a\u0442\u043e\u0440 Rgith<\/li>\n<\/ul>\n\t\t\n<style>\n#text-486583406 {\n  color: rgb(0,0,0);\n}\n#text-486583406 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small align-middle\"  id=\"row-1737548525\">\n\n\n\t<div id=\"col-610983270\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_280202900\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1000\" height=\"540\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-1-Male-to-2-Female.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-1-Male-to-2-Female.jpg 1000w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-1-Male-to-2-Female-300x162.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-1-Male-to-2-Female-768x415.jpg 768w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/M12-5Pin-1-Male-to-2-Female-600x324.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_280202900 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-610983270 > .col-inner {\n  margin: 8px 8px 8px 8px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1741791479\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1045338214\" class=\"text\">\n\t\t\n\n<h2>M12 - M12<\/h2>\r\n<ul>\r\n<li>12-\u043a\u043e\u043d\u0442\u0430\u043a\u0442\u043d\u044b\u0439 \u043c\u0443\u0436\u0441\u043a\u043e\u0439 \u0441 2 \u0436\u0435\u043d\u0441\u043a\u0438\u043c\u0438<\/li>\r\n<li>\u041a\u0430\u0431\u0435\u043b\u044c \u041f\u0412\u0425 \u0434\u043b\u0438\u043d\u043e\u0439 1,0 \u043c<\/li>\r\n<li>\u0412\u043e\u0434\u043e\u043d\u0435\u043f\u0440\u043e\u043d\u0438\u0446\u0430\u0435\u043c\u043e\u0441\u0442\u044c \u043f\u043e \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u0443 IP67<\/li>\r\n<\/ul>\n\t\t\n<style>\n#text-1045338214 {\n  color: rgb(0,0,0);\n}\n#text-1045338214 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t\n<style>\n#slider-1516711861 .flickity-slider > * {\n  max-width: 78%!important;\n}\n<\/style>\n<\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_762707623 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n<style>.slider-nav-light .flickity-prev-next-button svg, .slider-nav-light .flickity-prev-next-button .arrow {\r\n    fill: var(--primary-color);\r\n}\r\n<\/style>\n\n","protected":false},"excerpt":{"rendered":"<p>\u0421\u0435\u0440\u0438\u044f \u043f\u0430\u043d\u0435\u043b\u044c\u043d\u044b\u0445 \u0440\u043e\u0437\u0435\u0442\u043e\u043a M12 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0442\u0440\u0438 \u0432\u0438\u0434\u0430 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f \u043d\u0430 \u0432\u044b\u0431\u043e\u0440: PCB Mount, Panel Mount &amp; Cable, \u0438 \u0438\u043c\u0435\u044e\u0442 \u0442\u0440\u0438 \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e\u0441\u0442\u0438 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f: \u041f\u0435\u0440\u0435\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0437\u0430\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0444\u043b\u0430\u043d\u0435\u0446 \u0441 4 \u043e\u0442\u0432\u0435\u0440\u0441\u0442\u0438\u044f\u043c\u0438. \u0412 \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0438 \u0441\u043e \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u043e\u043c IEC 61076-2-101\/104, \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0443\u0435\u0442 \u0443\u0440\u043e\u0432\u043d\u044e \u0437\u0430\u0449\u0438\u0442\u044b IP67.<\/p>\n","protected":false},"featured_media":58355,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2729,2654,2655,2730],"product_tag":[],"class_list":["post-61269","product","type-product","status-publish","has-post-thumbnail","product_cat-2729","product_cat-m-","product_cat-m12-ru","product_cat---m12","pa_ingress-protection-ip67-ru","pa_ingress-protection-ip68-ru","pa_orientation-2644","pa_termination-2695","first","instock","shipping-taxable","product-type-variable"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12 - Renhotec Pro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12 - Renhotec Pro\" \/>\n<meta property=\"og:description\" content=\"\u0421\u0435\u0440\u0438\u044f \u043f\u0430\u043d\u0435\u043b\u044c\u043d\u044b\u0445 \u0440\u043e\u0437\u0435\u0442\u043e\u043a M12 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0442\u0440\u0438 \u0432\u0438\u0434\u0430 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f \u043d\u0430 \u0432\u044b\u0431\u043e\u0440: PCB Mount, Panel Mount &amp; Cable, \u0438 \u0438\u043c\u0435\u044e\u0442 \u0442\u0440\u0438 \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e\u0441\u0442\u0438 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f: \u041f\u0435\u0440\u0435\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0437\u0430\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0444\u043b\u0430\u043d\u0435\u0446 \u0441 4 \u043e\u0442\u0432\u0435\u0440\u0441\u0442\u0438\u044f\u043c\u0438. \u0412 \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0438 \u0441\u043e \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u043e\u043c IEC 61076-2-101\/104, \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0443\u0435\u0442 \u0443\u0440\u043e\u0432\u043d\u044e \u0437\u0430\u0449\u0438\u0442\u044b IP67.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/\" \/>\n<meta property=\"og:site_name\" content=\"Renhotec Pro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100070365603319\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/m12-flange-4pin.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/\",\"name\":\"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12 - Renhotec Pro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/m12-flange-4pin.jpg\",\"datePublished\":\"2022-02-15T01:40:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/m12-flange-4pin.jpg\",\"contentUrl\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/m12-flange-4pin.jpg\",\"width\":750,\"height\":750,\"caption\":\"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/product\\\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f\",\"item\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All Products\",\"item\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/\",\"name\":\"Renhotec Pro\",\"description\":\"Professional Cable &amp; Connector Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#organization\",\"name\":\"Renhotec PRO\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/renhtoec-logo-dark.png\",\"contentUrl\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/renhtoec-logo-dark.png\",\"width\":699,\"height\":116,\"caption\":\"Renhotec PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100070365603319\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/shenzhen-renhotec-technology-electronics-co--ltd\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12 - Renhotec Pro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/","og_locale":"ru_RU","og_type":"article","og_title":"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12 - Renhotec Pro","og_description":"\u0421\u0435\u0440\u0438\u044f \u043f\u0430\u043d\u0435\u043b\u044c\u043d\u044b\u0445 \u0440\u043e\u0437\u0435\u0442\u043e\u043a M12 \u043e\u0431\u0435\u0441\u043f\u0435\u0447\u0438\u0432\u0430\u0435\u0442 \u0442\u0440\u0438 \u0432\u0438\u0434\u0430 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f \u043d\u0430 \u0432\u044b\u0431\u043e\u0440: PCB Mount, Panel Mount &amp; Cable, \u0438 \u0438\u043c\u0435\u044e\u0442 \u0442\u0440\u0438 \u043e\u0441\u043e\u0431\u0435\u043d\u043d\u043e\u0441\u0442\u0438 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u044f: \u041f\u0435\u0440\u0435\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0437\u0430\u0434\u043d\u0435\u0435 \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435, \u0444\u043b\u0430\u043d\u0435\u0446 \u0441 4 \u043e\u0442\u0432\u0435\u0440\u0441\u0442\u0438\u044f\u043c\u0438. \u0412 \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0438\u0438 \u0441\u043e \u0441\u0442\u0430\u043d\u0434\u0430\u0440\u0442\u043e\u043c IEC 61076-2-101\/104, \u0441\u043e\u043e\u0442\u0432\u0435\u0442\u0441\u0442\u0432\u0443\u0435\u0442 \u0443\u0440\u043e\u0432\u043d\u044e \u0437\u0430\u0449\u0438\u0442\u044b IP67.","og_url":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/","og_site_name":"Renhotec Pro","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100070365603319","og_image":[{"width":750,"height":750,"url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/m12-flange-4pin.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/","url":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/","name":"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12 - Renhotec Pro","isPartOf":{"@id":"https:\/\/renhotecpro.com\/ru\/#website"},"primaryImageOfPage":{"@id":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/#primaryimage"},"image":{"@id":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/#primaryimage"},"thumbnailUrl":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/m12-flange-4pin.jpg","datePublished":"2022-02-15T01:40:51+00:00","breadcrumb":{"@id":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/"]}]},{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/#primaryimage","url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/m12-flange-4pin.jpg","contentUrl":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2022\/02\/m12-flange-4pin.jpg","width":750,"height":750,"caption":"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12"},{"@type":"BreadcrumbList","@id":"https:\/\/renhotecpro.com\/ru\/product\/%d0%b6%d0%b3%d1%83%d1%82-%d0%bf%d1%80%d0%be%d0%b2%d0%be%d0%b4%d0%be%d0%b2-%d1%81-%d1%84%d0%bb%d0%b0%d0%bd%d1%86%d0%b5%d0%b2%d1%8b%d0%bc-%d0%ba%d1%80%d0%b5%d0%bf%d0%bb%d0%b5%d0%bd%d0%b8%d0%b5%d0%bc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","item":"https:\/\/renhotecpro.com\/ru\/"},{"@type":"ListItem","position":2,"name":"All Products","item":"https:\/\/renhotecpro.com\/ru\/shop\/"},{"@type":"ListItem","position":3,"name":"\u0416\u0433\u0443\u0442 \u043f\u0440\u043e\u0432\u043e\u0434\u043e\u0432 \u0441 \u0444\u043b\u0430\u043d\u0446\u0435\u0432\u044b\u043c \u043a\u0440\u0435\u043f\u043b\u0435\u043d\u0438\u0435\u043c \u0441 \u0433\u043d\u0435\u0437\u0434\u043e\u043c M12"}]},{"@type":"WebSite","@id":"https:\/\/renhotecpro.com\/ru\/#website","url":"https:\/\/renhotecpro.com\/ru\/","name":"Renhotec Pro","description":"Professional Cable &amp; Connector Manufacturer","publisher":{"@id":"https:\/\/renhotecpro.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renhotecpro.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/renhotecpro.com\/ru\/#organization","name":"Renhotec PRO","url":"https:\/\/renhotecpro.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/renhotecpro.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2025\/06\/renhtoec-logo-dark.png","contentUrl":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2025\/06\/renhtoec-logo-dark.png","width":699,"height":116,"caption":"Renhotec PRO"},"image":{"@id":"https:\/\/renhotecpro.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100070365603319","https:\/\/www.linkedin.com\/company\/shenzhen-renhotec-technology-electronics-co--ltd\/"]}]}},"_links":{"self":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/product\/61269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/media\/58355"}],"wp:attachment":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/media?parent=61269"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/product_brand?post=61269"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/product_cat?post=61269"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/product_tag?post=61269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}