{"id":43248,"date":"2017-05-11T11:13:06","date_gmt":"2017-05-11T03:13:06","guid":{"rendered":"http:\/\/www.renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg"},"modified":"2017-05-11T11:13:06","modified_gmt":"2017-05-11T03:13:06","slug":"mc4-connector-solar-cable-assemblies-male-and-cable-2-2","status":"inherit","type":"attachment","link":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/","title":{"rendered":"MC4 Connector Solar Cable Assemblies Male and Cable"},"author":12,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-43248","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MC4 Connector Solar Cable Assemblies Male and Cable - Renhotec Pro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/\" \/>\n<meta property=\"og:locale\" content=\"ru_RU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MC4 Connector Solar Cable Assemblies Male and Cable - Renhotec Pro\" \/>\n<meta property=\"og:description\" content=\"MC4 Connector Solar Cable Assemblies Male and Cable\" \/>\n<meta property=\"og:url\" content=\"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Renhotec Pro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100070365603319\" \/>\n<meta property=\"og:image\" content=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\\\/\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\\\/\",\"name\":\"MC4 Connector Solar Cable Assemblies Male and Cable - Renhotec Pro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#website\"},\"datePublished\":\"2017-05-11T03:13:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\\\/#breadcrumb\"},\"inLanguage\":\"ru-RU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f\",\"item\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MC4 Connector Solar Cable Assemblies Male and Cable\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#website\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/\",\"name\":\"Renhotec Pro\",\"description\":\"Professional Cable &amp; Connector Manufacturer\",\"publisher\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ru-RU\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#organization\",\"name\":\"Renhotec PRO\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ru-RU\",\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/renhtoec-logo-dark.png\",\"contentUrl\":\"https:\\\/\\\/renhotecpro.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/renhtoec-logo-dark.png\",\"width\":699,\"height\":116,\"caption\":\"Renhotec PRO\"},\"image\":{\"@id\":\"https:\\\/\\\/renhotecpro.com\\\/ru\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100070365603319\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/shenzhen-renhotec-technology-electronics-co--ltd\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MC4 Connector Solar Cable Assemblies Male and Cable - Renhotec Pro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/","og_locale":"ru_RU","og_type":"article","og_title":"MC4 Connector Solar Cable Assemblies Male and Cable - Renhotec Pro","og_description":"MC4 Connector Solar Cable Assemblies Male and Cable","og_url":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/","og_site_name":"Renhotec Pro","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100070365603319","og_image":[{"width":600,"height":600,"url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/","url":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/","name":"MC4 Connector Solar Cable Assemblies Male and Cable - Renhotec Pro","isPartOf":{"@id":"https:\/\/renhotecpro.com\/ru\/#website"},"datePublished":"2017-05-11T03:13:06+00:00","breadcrumb":{"@id":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/#breadcrumb"},"inLanguage":"ru-RU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/renhotecpro.com\/ru\/mc4-connector-solar-cable-assemblies-male-and-cable-2-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f","item":"https:\/\/renhotecpro.com\/ru\/"},{"@type":"ListItem","position":2,"name":"MC4 Connector Solar Cable Assemblies Male and Cable"}]},{"@type":"WebSite","@id":"https:\/\/renhotecpro.com\/ru\/#website","url":"https:\/\/renhotecpro.com\/ru\/","name":"Renhotec Pro","description":"Professional Cable &amp; Connector Manufacturer","publisher":{"@id":"https:\/\/renhotecpro.com\/ru\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/renhotecpro.com\/ru\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ru-RU"},{"@type":"Organization","@id":"https:\/\/renhotecpro.com\/ru\/#organization","name":"Renhotec PRO","url":"https:\/\/renhotecpro.com\/ru\/","logo":{"@type":"ImageObject","inLanguage":"ru-RU","@id":"https:\/\/renhotecpro.com\/ru\/#\/schema\/logo\/image\/","url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2025\/06\/renhtoec-logo-dark.png","contentUrl":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2025\/06\/renhtoec-logo-dark.png","width":699,"height":116,"caption":"Renhotec PRO"},"image":{"@id":"https:\/\/renhotecpro.com\/ru\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100070365603319","https:\/\/www.linkedin.com\/company\/shenzhen-renhotec-technology-electronics-co--ltd\/"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg'><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg 300w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-100x100.jpg 100w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-80x80.jpg 80w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-36x36.jpg 36w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-180x180.jpg 180w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-450x450.jpg 450w, https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>MC4 Connector Solar Cable Assemblies Male and Cable<\/p>\n"},"caption":{"rendered":"<p>MC4 Connector Solar Cable Assemblies Male and Cable<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":600,"file":"2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg","sizes":{"woocommerce_thumbnail":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg","width":300,"height":300,"uncropped":false,"filesize":8859,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg"},"woocommerce_gallery_thumbnail":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-100x100.jpg","width":100,"height":100,"filesize":1956,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-100x100.jpg"},"thumbnail":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-80x80.jpg","width":80,"height":80,"filesize":1488,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-80x80.jpg"},"medium":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg","width":300,"height":300,"filesize":8859,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg"},"widget":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-36x36.jpg","width":36,"height":36,"filesize":725,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-36x36.jpg"},"square":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-180x180.jpg","width":180,"height":180,"filesize":4397,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-180x180.jpg"},"featured":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x430.jpg","width":600,"height":430,"filesize":21359,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x430.jpg"},"portfolio":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-495x400.jpg","width":495,"height":400,"filesize":15896,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-495x400.jpg"},"portfolio_small":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-260x185.jpg","width":260,"height":185,"filesize":6610,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-260x185.jpg"},"magazine":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x375.jpg","width":600,"height":375,"filesize":17559,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x375.jpg"},"entry_with_sidebar":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x321.jpg","width":600,"height":321,"filesize":21159,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x321.jpg"},"entry_without_sidebar":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x423.jpg","width":600,"height":423,"filesize":17612,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-600x423.jpg"},"shop_thumbnail":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-100x100.jpg","width":100,"height":100,"filesize":1956,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-100x100.jpg"},"shop_catalog":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg","width":300,"height":300,"uncropped":false,"filesize":8859,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-300x300.jpg"},"shop_single":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-450x450.jpg","width":450,"height":450,"filesize":15817,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable-450x450.jpg"},"full":{"file":"MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg","width":600,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"ShortPixel":{"WaitingProcessing":true},"filesize":18765},"post":null,"source_url":"https:\/\/renhotecpro.com\/wp-content\/uploads\/2017\/05\/MC4-Connector-Solar-Cable-Assemblies-Male-and-Cable.jpg","_links":{"self":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/media\/43248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/renhotecpro.com\/ru\/wp-json\/wp\/v2\/comments?post=43248"}]}}